{"id":1320,"date":"2017-03-29T13:35:20","date_gmt":"2017-03-29T11:35:20","guid":{"rendered":"http:\/\/sportland.bz\/verleih\/"},"modified":"2017-05-18T17:06:43","modified_gmt":"2017-05-18T15:06:43","slug":"verleih","status":"publish","type":"page","link":"http:\/\/sportland.bz\/it\/verleih\/","title":{"rendered":"Noleggio"},"content":{"rendered":"<p>[vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;grid&#8221; text_align=&#8221;left&#8221; css_animation=&#8221;&#8221;][vc_column][vc_empty_space height=&#8221;50px&#8221;][vc_accordion active_tab=&#8221;1&#8243; collapsible=&#8221;yes&#8221; style=&#8221;accordion&#8221;][vc_accordion_tab title=&#8221;Attrezzatura per scialpinismo&#8221; title_tag=&#8221;h2&#8243;][vc_empty_space][vc_single_image image=&#8221;1024&#8243; img_size=&#8221;full&#8221; qode_css_animation=&#8221;&#8221;][vc_empty_space][vc_column_text]<\/p>\n<h3 style=\"text-align: left;\">Attrezzatura per scialpinismo<\/h3>\n<p>Da noi potete noleggiare tutto ci\u00f2 che vi serve per la prossima escursione con gli sci d\u2019alpinismo. Tuttavia, la cosa pi\u00f9 bella \u00e8 che potete testare gli ultimi modelli della stagione.[\/vc_column_text][vc_empty_space][\/vc_accordion_tab][vc_accordion_tab title=&#8221;Attrezzatura per ferrate&#8221; title_tag=&#8221;h2&#8243;][vc_empty_space][vc_single_image image=&#8221;1023&#8243; img_size=&#8221;full&#8221; qode_css_animation=&#8221;&#8221;][vc_empty_space][vc_column_text]<\/p>\n<h3 style=\"text-align: left;\">Attrezzatura per ferrate<\/h3>\n<p>Vie ferrate vanno di moda ultimamente. Che cosa stai aspettando? Punta in alto con la nostra attrezzatura per ferrate: da noi puoi noleggiare cinture, caschi e set da ferrata per te e la tua famiglia.[\/vc_column_text][vc_empty_space][\/vc_accordion_tab][vc_accordion_tab title=&#8221;Attrezzatura per tour in montagna&#8221; title_tag=&#8221;h2&#8243;][vc_empty_space][vc_single_image image=&#8221;1022&#8243; img_size=&#8221;full&#8221; qode_css_animation=&#8221;&#8221;][vc_empty_space][vc_column_text]<\/p>\n<h3 style=\"text-align: left;\">Attrezzatura per tour in montagna<\/h3>\n<p style=\"text-align: left;\">I tour in montagna sono sempre un\u2019esperienza unica, soprattutto per la vista panoramica. Noi ti noleggiamo ramponi, cavi, viti da ghiaccio, piccozze, cinture e caschi. Per momenti indimenticabili in montagna.<\/p>\n<p>[\/vc_column_text][vc_empty_space][\/vc_accordion_tab][vc_accordion_tab title=&#8221;Attrezzatura per arrampicate su ghiaccio&#8221; title_tag=&#8221;h2&#8243;][vc_empty_space][vc_single_image image=&#8221;1021&#8243; img_size=&#8221;full&#8221; qode_css_animation=&#8221;&#8221;][vc_empty_space][vc_column_text]<\/p>\n<h3 style=\"text-align: left;\">Attrezzatura per arrampicate su ghiaccio<\/h3>\n<p>Ramponi, apparecchi e vita da ghiaccio, cinture e caschi: da noi puoi noleggiare tutta l\u2019attrezzatura per arrampicate su ghiaccio. Vieni a trovarci nel nostro negozio a S. Leonardo in Passiria.[\/vc_column_text][vc_empty_space][\/vc_accordion_tab][\/vc_accordion][vc_empty_space height=&#8221;60px&#8221;][\/vc_column][\/vc_row][vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; text_align=&#8221;left&#8221; css_animation=&#8221;&#8221;][vc_column][qode_elements_holder number_of_columns=&#8221;three_columns&#8221;][qode_elements_holder_item background_color=&#8221;#f9f9f9&#8243; background_image=&#8221;1013&#8243; item_padding_1024_1280=&#8221;40%&#8221; item_padding_768_1024=&#8221;30%&#8221; item_padding_600_768=&#8221;30%&#8221; item_padding_480_600=&#8221;40%&#8221; item_padding_480=&#8221;40%&#8221;][vc_empty_space height=&#8221;0&#8243;][\/qode_elements_holder_item][qode_elements_holder_item background_color=&#8221;#f2f2f2&#8243; item_padding=&#8221;14% 11% 14% 14%&#8221; vertical_alignment=&#8221;middle&#8221; item_padding_1280_1600=&#8221;10% 5% 10% 5%&#8221; item_padding_1024_1280=&#8221;0 5% 0 5%&#8221; item_padding_768_1024=&#8221;8% 10% 8% 8%&#8221; item_padding_600_768=&#8221;15% 15% 15% 15%&#8221; item_padding_480_600=&#8221;8% 8% 8% 8%&#8221; item_padding_480=&#8221;8% 8% 8% 8%&#8221;][vc_column_text]<\/p>\n<h3>Il nostro servizio<\/h3>\n<p>[\/vc_column_text][vc_separator type=&#8221;transparent&#8221; border_style=&#8221;&#8221; up=&#8221;22&#8243;][vc_column_text]Noi pretendiamo molto, sia da noi che dal nostro servizio. Secondo il motto &#8220;non va bene, non c&#8217;\u00e8!\u201d proviamo sempre a risolvere ogni problema.[\/vc_column_text][vc_separator type=&#8221;transparent&#8221; border_style=&#8221;&#8221; up=&#8221;35&#8243;]<a href=\"sportland.bz\/?p=671\" target=\"_self\" data-hover-color=#ffffff class=\"qbutton  small\" style=\"color: #ffffff; \">Leggi di pi\u00f9<\/a>[\/qode_elements_holder_item][qode_elements_holder_item background_color=&#8221;#f9f9f9&#8243; background_image=&#8221;501&#8243; item_padding_1024_1280=&#8221;40%&#8221; item_padding_768_1024=&#8221;30%&#8221; item_padding_600_768=&#8221;30%&#8221; item_padding_480_600=&#8221;40%&#8221; item_padding_480=&#8221;40%&#8221;][vc_empty_space height=&#8221;0&#8243;][\/qode_elements_holder_item][\/qode_elements_holder][\/vc_column][\/vc_row][vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; text_align=&#8221;left&#8221; css_animation=&#8221;&#8221;][vc_column][vc_empty_space height=&#8221;50px&#8221;]<div class='qode_carousels_holder clearfix hover_second_image'><div class='qode_carousels ' data-number_of_items = 5><ul class='slides'><li class='item'><div class=\"carousel_item_holder\"><a href='sportland.bz\/?p=722' target='_self'><span class='first_image_holder has_hover_image'><img src='http:\/\/sportland.bz\/wordpress\/wp-content\/uploads\/2017\/03\/Montura.gif' alt='Montura'><\/span><span class='second_image_holder has_hover_image'><img src='http:\/\/sportland.bz\/wordpress\/wp-content\/uploads\/2017\/03\/Montura_hover.gif' alt='Montura'><\/span><\/a><\/div><\/li><li class='item'><div class=\"carousel_item_holder\"><a href='sportland.bz\/?p=722' target='_self'><span class='first_image_holder has_hover_image'><img src='http:\/\/sportland.bz\/wordpress\/wp-content\/uploads\/2017\/03\/Dynafit.gif' alt='Dynafit'><\/span><span class='second_image_holder has_hover_image'><img src='http:\/\/sportland.bz\/wordpress\/wp-content\/uploads\/2017\/03\/Dynafit_hover.gif' alt='Dynafit'><\/span><\/a><\/div><\/li><li class='item'><div class=\"carousel_item_holder\"><a href='sportland.bz\/?p=722' target='_self'><span class='first_image_holder has_hover_image'><img src='http:\/\/sportland.bz\/wordpress\/wp-content\/uploads\/2017\/03\/Ortovox.gif' alt='Ortovox'><\/span><span class='second_image_holder has_hover_image'><img src='http:\/\/sportland.bz\/wordpress\/wp-content\/uploads\/2017\/03\/Ortovox_hover.gif' alt='Ortovox'><\/span><\/a><\/div><\/li><li class='item'><div class=\"carousel_item_holder\"><a href='sportland.bz\/?p=722' target='_self'><span class='first_image_holder has_hover_image'><img src='http:\/\/sportland.bz\/wordpress\/wp-content\/uploads\/2017\/03\/Petzl.gif' alt='Petzl'><\/span><span class='second_image_holder has_hover_image'><img src='http:\/\/sportland.bz\/wordpress\/wp-content\/uploads\/2017\/03\/Petzl_hover.gif' alt='Petzl'><\/span><\/a><\/div><\/li><li class='item'><div class=\"carousel_item_holder\"><a href='sportland.bz\/?p=722' target='_self'><span class='first_image_holder has_hover_image'><img src='http:\/\/sportland.bz\/wordpress\/wp-content\/uploads\/2017\/03\/Salewa.gif' alt='Salewa'><\/span><span class='second_image_holder has_hover_image'><img src='http:\/\/sportland.bz\/wordpress\/wp-content\/uploads\/2017\/03\/Salewa_hover.gif' alt='Salewa'><\/span><\/a><\/div><\/li><li class='item'><div class=\"carousel_item_holder\"><a href='sportland.bz\/?p=722' target='_self'><span class='first_image_holder has_hover_image'><img src='http:\/\/sportland.bz\/wordpress\/wp-content\/uploads\/2017\/03\/Sportiva.gif' alt='La Sportiva'><\/span><span class='second_image_holder has_hover_image'><img src='http:\/\/sportland.bz\/wordpress\/wp-content\/uploads\/2017\/03\/Sportiva_hover.gif' alt='La Sportiva'><\/span><\/a><\/div><\/li><li class='item'><div class=\"carousel_item_holder\"><a href='sportland.bz\/?p=722' target='_self'><span class='first_image_holder has_hover_image'><img src='http:\/\/sportland.bz\/wordpress\/wp-content\/uploads\/2017\/05\/CMP.gif' alt='CMP'><\/span><span class='second_image_holder has_hover_image'><img src='http:\/\/sportland.bz\/wordpress\/wp-content\/uploads\/2017\/05\/CMP_hover.gif' alt='CMP'><\/span><\/a><\/div><\/li><li class='item'><div class=\"carousel_item_holder\"><a href='sportland.bz\/?p=722' target='_self'><span class='first_image_holder has_hover_image'><img src='http:\/\/sportland.bz\/wordpress\/wp-content\/uploads\/2017\/05\/Maloja.gif' alt='Maloja'><\/span><span class='second_image_holder has_hover_image'><img src='http:\/\/sportland.bz\/wordpress\/wp-content\/uploads\/2017\/05\/Maloja_hover.gif' alt='Maloja'><\/span><\/a><\/div><\/li><\/ul><ul class=\"caroufredsel-direction-nav\"><li class=\"caroufredsel-prev-holder\"><a id=\"caroufredsel-prev\" class=\"qode_carousel_prev caroufredsel-navigation-item caroufredsel-prev\" href=\"javascript: void(0)\"><span class=\"arrow_carrot-left\"><\/span><\/a><\/li><li class=\"caroufredsel-next-holder\"><a class=\"qode_carousel_next caroufredsel-next caroufredsel-navigation-item\" id=\"caroufredsel-next\" href=\"javascript: void(0)\"><span class=\"arrow_carrot-right\"><\/span><\/a><\/li><\/ul><\/div><\/div>[vc_empty_space height=&#8221;50px&#8221;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;grid&#8221; text_align=&#8221;left&#8221; css_animation=&#8221;&#8221;][vc_column][vc_empty_space height=&#8221;50px&#8221;][vc_accordion active_tab=&#8221;1&#8243; collapsible=&#8221;yes&#8221; style=&#8221;accordion&#8221;][vc_accordion_tab title=&#8221;Attrezzatura per scialpinismo&#8221; title_tag=&#8221;h2&#8243;][vc_empty_space][vc_single_image image=&#8221;1024&#8243; img_size=&#8221;full&#8221; qode_css_animation=&#8221;&#8221;][vc_empty_space][vc_column_text] Attrezzatura per scialpinismo Da noi potete noleggiare tutto ci\u00f2 che vi serve per la prossima escursione con gli sci d\u2019alpinismo. Tuttavia, la cosa pi\u00f9 bella \u00e8 che potete&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":[],"_links":{"self":[{"href":"http:\/\/sportland.bz\/it\/wp-json\/wp\/v2\/pages\/1320"}],"collection":[{"href":"http:\/\/sportland.bz\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/sportland.bz\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/sportland.bz\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/sportland.bz\/it\/wp-json\/wp\/v2\/comments?post=1320"}],"version-history":[{"count":1,"href":"http:\/\/sportland.bz\/it\/wp-json\/wp\/v2\/pages\/1320\/revisions"}],"predecessor-version":[{"id":1322,"href":"http:\/\/sportland.bz\/it\/wp-json\/wp\/v2\/pages\/1320\/revisions\/1322"}],"wp:attachment":[{"href":"http:\/\/sportland.bz\/it\/wp-json\/wp\/v2\/media?parent=1320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}